{"id":428,"date":"2016-12-30T11:14:56","date_gmt":"2016-12-30T10:14:56","guid":{"rendered":"https:\/\/fonderiesdesougland.fr\/de\/?p=428"},"modified":"2017-01-13T11:08:40","modified_gmt":"2017-01-13T10:08:40","slug":"erweiterte-offnungszeiten","status":"publish","type":"post","link":"https:\/\/fonderiesdesougland.fr\/de\/2016\/12\/30\/erweiterte-offnungszeiten\/","title":{"rendered":"Erweiterte \u00d6ffnungszeiten !"},"content":{"rendered":"<div id=\"pl-428\"  class=\"panel-layout\" ><div id=\"pg-428-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-428-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-428-0-0-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-428\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/fonderiesdesougland.fr\/de\/wp-content\/uploads\/sites\/5\/2016\/11\/img-actu-1.jpg\" width=\"800\" height=\"600\" srcset=\"https:\/\/fonderiesdesougland.fr\/de\/wp-content\/uploads\/sites\/5\/2016\/11\/img-actu-1.jpg 800w, https:\/\/fonderiesdesougland.fr\/de\/wp-content\/uploads\/sites\/5\/2016\/11\/img-actu-1-300x225.jpg 300w, https:\/\/fonderiesdesougland.fr\/de\/wp-content\/uploads\/sites\/5\/2016\/11\/img-actu-1-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" alt=\"https:\/\/fonderiesdesougland.fr\/wp-content\/uploads\/2016\/11\/img-actu-1.jpg\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><div id=\"pgc-428-0-1\"  class=\"panel-grid-cell\" ><div id=\"panel-428-0-1-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><strong>Wir stehen Ihnen k\u00fcnftig von Montag, 8 Uhr, bis Samstag, 12 Uhr, zur Verf\u00fcgung !<\/strong><\/p>\n<p>\u2022 Erh\u00f6hte Verf\u00fcgbarkeit<br \/>\u2022 Die besten L\u00f6sungen f\u00fcr Ihren Bedarf<br \/>\u2022 Kurze Antwort-, Fertigungs- und Versandfristen<\/p>\n<p>\u00a0<\/p>\n<p><strong>W\u00e4hlen Sie Ihr bevorzugtes Kommunikationsmittel :<\/strong><br \/>Telefon : +33 (0)3 23 99 36 36<br \/>E-mail : <a href=\"mailto:fonderie.sougland@wanadoo.fr\">fonderie.sougland@orange.fr<\/a><br \/>Fax : +33 (0)3 23 98 74 06<br \/>FONDERIES DE SOUGLAND 2 AVENUE DE SOUGLAND 02830 SAINT-MICHEL France<\/p>\n<ul>\n<li id=\"link64_adl_tabid\" style=\"display: none;\" data-url=\"https:\/\/fonderiesdesougland.fr\/de\/wp-admin\/post.php?post=428&amp;action=edit\">140<\/li>\n<\/ul>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Wir stehen Ihnen k\u00fcnftig von Montag, 8 Uhr, bis Samstag, 12 Uhr, zur Verf\u00fcgung !\u2022 Erh\u00f6hte Verf\u00fcgbarkeit\u2022 Die besten L\u00f6sungen f\u00fcr Ihren Bedarf\u2022 Kurze Antwort-, Fertigungs- und Versandfristen\u00a0W\u00e4hlen Sie Ihr bevorzugtes Kommunikationsmittel :Telefon : +33 (0)3 23 99 36 36E-mail : fonderie.sougland@orange.frFax : +33 (0)3 23 98 74 06FONDERIES DE SOUGLAND 2 AVENUE DE SOUGLAND [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-428","post","type-post","status-publish","format-standard","hentry","category-aktuelles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Erweiterte \u00d6ffnungszeiten ! - Sougland Gie\u00dferei<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fonderiesdesougland.fr\/de\/2016\/12\/30\/erweiterte-offnungszeiten\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Erweiterte \u00d6ffnungszeiten ! - Sougland Gie\u00dferei\" \/>\n<meta property=\"og:description\" content=\"Wir stehen Ihnen k\u00fcnftig von Montag, 8 Uhr, bis Samstag, 12 Uhr, zur Verf\u00fcgung !\u2022 Erh\u00f6hte Verf\u00fcgbarkeit\u2022 Die besten L\u00f6sungen f\u00fcr Ihren Bedarf\u2022 Kurze Antwort-, Fertigungs- und Versandfristen\u00a0W\u00e4hlen Sie Ihr bevorzugtes Kommunikationsmittel :Telefon : +33 (0)3 23 99 36 36E-mail : fonderie.sougland@orange.frFax : +33 (0)3 23 98 74 06FONDERIES DE SOUGLAND 2 AVENUE DE SOUGLAND [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fonderiesdesougland.fr\/de\/2016\/12\/30\/erweiterte-offnungszeiten\/\" \/>\n<meta property=\"og:site_name\" content=\"Sougland Gie\u00dferei\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-30T10:14:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-01-13T10:08:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fonderiesdesougland.fr\/de\/wp-content\/uploads\/sites\/5\/2016\/11\/img-actu-1.jpg\" \/>\n<meta name=\"author\" content=\"\u00c9QUINOXES\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u00c9QUINOXES\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fonderiesdesougland.fr\\\/de\\\/2016\\\/12\\\/30\\\/erweiterte-offnungszeiten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fonderiesdesougland.fr\\\/de\\\/2016\\\/12\\\/30\\\/erweiterte-offnungszeiten\\\/\"},\"author\":{\"name\":\"\u00c9QUINOXES\",\"@id\":\"https:\\\/\\\/fonderiesdesougland.fr\\\/de\\\/#\\\/schema\\\/person\\\/85af23217b3adf5db636186619e3e067\"},\"headline\":\"Erweiterte \u00d6ffnungszeiten !\",\"datePublished\":\"2016-12-30T10:14:56+00:00\",\"dateModified\":\"2017-01-13T10:08:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fonderiesdesougland.fr\\\/de\\\/2016\\\/12\\\/30\\\/erweiterte-offnungszeiten\\\/\"},\"wordCount\":66,\"image\":{\"@id\":\"https:\\\/\\\/fonderiesdesougland.fr\\\/de\\\/2016\\\/12\\\/30\\\/erweiterte-offnungszeiten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fonderiesdesougland.fr\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2016\\\/11\\\/img-actu-1.jpg\",\"articleSection\":[\"Aktuelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fonderiesdesougland.fr\\\/de\\\/2016\\\/12\\\/30\\\/erweiterte-offnungszeiten\\\/\",\"url\":\"https:\\\/\\\/fonderiesdesougland.fr\\\/de\\\/2016\\\/12\\\/30\\\/erweiterte-offnungszeiten\\\/\",\"name\":\"Erweiterte \u00d6ffnungszeiten ! - Sougland Gie\u00dferei\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fonderiesdesougland.fr\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fonderiesdesougland.fr\\\/de\\\/2016\\\/12\\\/30\\\/erweiterte-offnungszeiten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fonderiesdesougland.fr\\\/de\\\/2016\\\/12\\\/30\\\/erweiterte-offnungszeiten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fonderiesdesougland.fr\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2016\\\/11\\\/img-actu-1.jpg\",\"datePublished\":\"2016-12-30T10:14:56+00:00\",\"dateModified\":\"2017-01-13T10:08:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fonderiesdesougland.fr\\\/de\\\/#\\\/schema\\\/person\\\/85af23217b3adf5db636186619e3e067\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fonderiesdesougland.fr\\\/de\\\/2016\\\/12\\\/30\\\/erweiterte-offnungszeiten\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fonderiesdesougland.fr\\\/de\\\/2016\\\/12\\\/30\\\/erweiterte-offnungszeiten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fonderiesdesougland.fr\\\/de\\\/2016\\\/12\\\/30\\\/erweiterte-offnungszeiten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fonderiesdesougland.fr\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2016\\\/11\\\/img-actu-1.jpg\",\"contentUrl\":\"https:\\\/\\\/fonderiesdesougland.fr\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2016\\\/11\\\/img-actu-1.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fonderiesdesougland.fr\\\/de\\\/2016\\\/12\\\/30\\\/erweiterte-offnungszeiten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/fonderiesdesougland.fr\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Erweiterte \u00d6ffnungszeiten !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fonderiesdesougland.fr\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/fonderiesdesougland.fr\\\/de\\\/\",\"name\":\"Sougland Gie\u00dferei\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fonderiesdesougland.fr\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fonderiesdesougland.fr\\\/de\\\/#\\\/schema\\\/person\\\/85af23217b3adf5db636186619e3e067\",\"name\":\"\u00c9QUINOXES\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b12de7e217fb7bea5cfe560f617eb621e85afe3b75078b77f28163bfde9dd515?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b12de7e217fb7bea5cfe560f617eb621e85afe3b75078b77f28163bfde9dd515?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b12de7e217fb7bea5cfe560f617eb621e85afe3b75078b77f28163bfde9dd515?s=96&d=mm&r=g\",\"caption\":\"\u00c9QUINOXES\"},\"url\":\"https:\\\/\\\/fonderiesdesougland.fr\\\/de\\\/author\\\/equinoxesadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Erweiterte \u00d6ffnungszeiten ! - Sougland Gie\u00dferei","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fonderiesdesougland.fr\/de\/2016\/12\/30\/erweiterte-offnungszeiten\/","og_locale":"fr_FR","og_type":"article","og_title":"Erweiterte \u00d6ffnungszeiten ! - Sougland Gie\u00dferei","og_description":"Wir stehen Ihnen k\u00fcnftig von Montag, 8 Uhr, bis Samstag, 12 Uhr, zur Verf\u00fcgung !\u2022 Erh\u00f6hte Verf\u00fcgbarkeit\u2022 Die besten L\u00f6sungen f\u00fcr Ihren Bedarf\u2022 Kurze Antwort-, Fertigungs- und Versandfristen\u00a0W\u00e4hlen Sie Ihr bevorzugtes Kommunikationsmittel :Telefon : +33 (0)3 23 99 36 36E-mail : fonderie.sougland@orange.frFax : +33 (0)3 23 98 74 06FONDERIES DE SOUGLAND 2 AVENUE DE SOUGLAND [&hellip;]","og_url":"https:\/\/fonderiesdesougland.fr\/de\/2016\/12\/30\/erweiterte-offnungszeiten\/","og_site_name":"Sougland Gie\u00dferei","article_published_time":"2016-12-30T10:14:56+00:00","article_modified_time":"2017-01-13T10:08:40+00:00","og_image":[{"url":"https:\/\/fonderiesdesougland.fr\/de\/wp-content\/uploads\/sites\/5\/2016\/11\/img-actu-1.jpg","type":"","width":"","height":""}],"author":"\u00c9QUINOXES","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u00c9QUINOXES"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fonderiesdesougland.fr\/de\/2016\/12\/30\/erweiterte-offnungszeiten\/#article","isPartOf":{"@id":"https:\/\/fonderiesdesougland.fr\/de\/2016\/12\/30\/erweiterte-offnungszeiten\/"},"author":{"name":"\u00c9QUINOXES","@id":"https:\/\/fonderiesdesougland.fr\/de\/#\/schema\/person\/85af23217b3adf5db636186619e3e067"},"headline":"Erweiterte \u00d6ffnungszeiten !","datePublished":"2016-12-30T10:14:56+00:00","dateModified":"2017-01-13T10:08:40+00:00","mainEntityOfPage":{"@id":"https:\/\/fonderiesdesougland.fr\/de\/2016\/12\/30\/erweiterte-offnungszeiten\/"},"wordCount":66,"image":{"@id":"https:\/\/fonderiesdesougland.fr\/de\/2016\/12\/30\/erweiterte-offnungszeiten\/#primaryimage"},"thumbnailUrl":"https:\/\/fonderiesdesougland.fr\/de\/wp-content\/uploads\/sites\/5\/2016\/11\/img-actu-1.jpg","articleSection":["Aktuelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/fonderiesdesougland.fr\/de\/2016\/12\/30\/erweiterte-offnungszeiten\/","url":"https:\/\/fonderiesdesougland.fr\/de\/2016\/12\/30\/erweiterte-offnungszeiten\/","name":"Erweiterte \u00d6ffnungszeiten ! - Sougland Gie\u00dferei","isPartOf":{"@id":"https:\/\/fonderiesdesougland.fr\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fonderiesdesougland.fr\/de\/2016\/12\/30\/erweiterte-offnungszeiten\/#primaryimage"},"image":{"@id":"https:\/\/fonderiesdesougland.fr\/de\/2016\/12\/30\/erweiterte-offnungszeiten\/#primaryimage"},"thumbnailUrl":"https:\/\/fonderiesdesougland.fr\/de\/wp-content\/uploads\/sites\/5\/2016\/11\/img-actu-1.jpg","datePublished":"2016-12-30T10:14:56+00:00","dateModified":"2017-01-13T10:08:40+00:00","author":{"@id":"https:\/\/fonderiesdesougland.fr\/de\/#\/schema\/person\/85af23217b3adf5db636186619e3e067"},"breadcrumb":{"@id":"https:\/\/fonderiesdesougland.fr\/de\/2016\/12\/30\/erweiterte-offnungszeiten\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fonderiesdesougland.fr\/de\/2016\/12\/30\/erweiterte-offnungszeiten\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fonderiesdesougland.fr\/de\/2016\/12\/30\/erweiterte-offnungszeiten\/#primaryimage","url":"https:\/\/fonderiesdesougland.fr\/de\/wp-content\/uploads\/sites\/5\/2016\/11\/img-actu-1.jpg","contentUrl":"https:\/\/fonderiesdesougland.fr\/de\/wp-content\/uploads\/sites\/5\/2016\/11\/img-actu-1.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/fonderiesdesougland.fr\/de\/2016\/12\/30\/erweiterte-offnungszeiten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/fonderiesdesougland.fr\/de\/"},{"@type":"ListItem","position":2,"name":"Erweiterte \u00d6ffnungszeiten !"}]},{"@type":"WebSite","@id":"https:\/\/fonderiesdesougland.fr\/de\/#website","url":"https:\/\/fonderiesdesougland.fr\/de\/","name":"Sougland Gie\u00dferei","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fonderiesdesougland.fr\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/fonderiesdesougland.fr\/de\/#\/schema\/person\/85af23217b3adf5db636186619e3e067","name":"\u00c9QUINOXES","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b12de7e217fb7bea5cfe560f617eb621e85afe3b75078b77f28163bfde9dd515?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b12de7e217fb7bea5cfe560f617eb621e85afe3b75078b77f28163bfde9dd515?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b12de7e217fb7bea5cfe560f617eb621e85afe3b75078b77f28163bfde9dd515?s=96&d=mm&r=g","caption":"\u00c9QUINOXES"},"url":"https:\/\/fonderiesdesougland.fr\/de\/author\/equinoxesadm\/"}]}},"_links":{"self":[{"href":"https:\/\/fonderiesdesougland.fr\/de\/wp-json\/wp\/v2\/posts\/428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fonderiesdesougland.fr\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fonderiesdesougland.fr\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fonderiesdesougland.fr\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fonderiesdesougland.fr\/de\/wp-json\/wp\/v2\/comments?post=428"}],"version-history":[{"count":8,"href":"https:\/\/fonderiesdesougland.fr\/de\/wp-json\/wp\/v2\/posts\/428\/revisions"}],"predecessor-version":[{"id":957,"href":"https:\/\/fonderiesdesougland.fr\/de\/wp-json\/wp\/v2\/posts\/428\/revisions\/957"}],"wp:attachment":[{"href":"https:\/\/fonderiesdesougland.fr\/de\/wp-json\/wp\/v2\/media?parent=428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fonderiesdesougland.fr\/de\/wp-json\/wp\/v2\/categories?post=428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fonderiesdesougland.fr\/de\/wp-json\/wp\/v2\/tags?post=428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}